{"id":13566,"date":"2020-11-09T09:00:45","date_gmt":"2020-11-09T08:00:45","guid":{"rendered":"https:\/\/my-life.lu\/?p=13566"},"modified":"2024-09-13T14:55:57","modified_gmt":"2024-09-13T12:55:57","slug":"welche-sprachen-spricht-man-in-luxemburg-59017","status":"publish","type":"post","link":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/","title":{"rendered":"Welche Sprachen spricht man in Luxemburg?"},"content":{"rendered":"<p class=\"entete\">Sie planen, nach Luxemburg auszuwandern und sich dort Arbeit zu suchen? Die meisten administrativen Schritte im Zusammenhang mit Ihren Auswanderungspl\u00e4nen haben Sie bereits erledigt, doch es gibt noch ein Thema, das Ihnen Sorgen bereitet: die Sprache Ihrer neuen Wahlheimat. Welche Sprache(n) sollte man wann und wo in diesem bekannterma\u00dfen mehrsprachigen Land verwenden? myLIFE gibt Ihnen einen \u00dcberblick \u00fcber die Verwendung der einzelnen Landessprachen Luxemburgs.<\/p>\n<p>Mo\u00efen, Bonjour, Bom dia, Hello, Hallo &#8230; Kein Zweifel \u2013 Sie sind in Luxemburg! Das wird schon nach wenigen Schritten durch die Hauptstadt klar. Sobald Sie etwas genauer hinh\u00f6ren, werden Sie feststellen, dass um Sie herum Luxemburgisch, Franz\u00f6sisch, Portugiesisch, Englisch, Deutsch und viele andere Sprachen gesprochen werden. Diese Sprachenvielfalt kommt dadurch zustande, dass in Luxemburg mehr als <a href=\"https:\/\/luxembourg.public.lu\/de\/gesellschaft-und-kultur\/bevolkerung\/demografie.html\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>47% Ausl\u00e4nder<\/strong><\/span><\/a> (170 verschiedener Nationalit\u00e4ten) leben. Hinzu kommen mehr als 228.000\u00a0Grenzpendler, die t\u00e4glich nach Luxemburg zur Arbeit fahren. Und nicht zuletzt wachsen die Luxemburger allgemein mehrsprachig auf. Daraus ergibt sich in Luxemburg ein wahres Potpourri der Kulturen, das f\u00fcr Neuank\u00f6mmlinge durchaus verwirrend sein kann.<\/p>\n<h2 id=\"h2_0\" >Drei offizielle Sprachen<\/h2>\n<p>Luxemburg hat seit der Verabschiedung des Gesetzes von 1984 \u00fcber die Mehrsprachigkeit drei offizielle Sprachen: Luxemburgisch (<em>L\u00ebtzebuergesch<\/em>), die offizielle Landessprache, sowie Franz\u00f6sisch und Deutsch, die beiden Verwaltungssprachen. Doch was den Gebrauch der einzelnen Sprachen betrifft, f\u00e4llt einem schnell auf, dass in diesem Land eine Vielzahl anderer Idiome koexistiert. W\u00e4hrend man im Norden und Osten eher Luxemburgisch und Deutsch spricht, sind in der Landesmitte und den s\u00fcdlichen Regionen Franz\u00f6sisch und Portugiesisch st\u00e4rker verbreitet. Dennoch ist in Bezug auf den Sprachgebrauch nicht die geographische Region ausschlaggebend, sondern der jeweilige Kontext. Wir m\u00f6chten diesen Punkt im Rahmen dieses Artikels jedoch nicht ersch\u00f6pfend behandeln, sondern vielmehr dabei helfen, die Gesamtsituation besser zu verstehen.<\/p>\n<blockquote><p>Um in Luxemburg eine Stelle zu finden, m\u00fcssen Sie in der Regel mindestens zwei Sprachen beherrschen. Doch die Wahl der am Arbeitsplatz gesprochenen Sprache h\u00e4ngt in erster Linie vom jeweiligen Wirtschaftssektor ab.<\/p><\/blockquote>\n<h2 id=\"h2_1\" >Die Verwendung der Sprachen h\u00e4ngt vom Wirtschaftssektor ab<\/h2>\n<p>Um in Luxemburg eine Stelle zu finden, m\u00fcssen Sie meist mindestens zwei Sprachen beherrschen, darunter Franz\u00f6sisch. Es ist die am h\u00e4ufigsten am Arbeitsplatz gesprochene Sprache (69,2%), gefolgt von Luxemburgisch (54,4%), Englisch (40%) und Deutsch (29,5%). Doch die Wahl der am Arbeitsplatz gesprochenen Sprache h\u00e4ngt in erster Linie vom jeweiligen Wirtschaftssektor ab.<\/p>\n<p>Wenngleich Franz\u00f6sisch die Sprache ist, die in den meisten Sektoren am h\u00e4ufigsten verwendet wird, ist im Finanz- und Versicherungssektor Englisch st\u00e4rker verbreitet. Englisch ist zudem unverzichtbar, wenn man sich in der Tourismus- oder IT-Branche bewerben m\u00f6chte. In der \u00f6ffentlichen Verwaltung ist hingegen Luxemburgisch vorherrschend, w\u00e4hrend im Handel und im Gastgewerbe (Hotels, Restaurants und Caf\u00e9s) haupts\u00e4chlich Franz\u00f6sisch gesprochen wird.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Die drei meistgesprochenen Sprachen 2021 nach Branche:<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24302\" src=\"https:\/\/my-life.lu\/wp-content\/uploads\/2020\/11\/Article_59017-2DE-e1726231730517.png\" alt=\"\" width=\"863\" height=\"833\" \/><\/p>\n<p><strong>Quelle<\/strong>: <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/statistiques.public.lu\/fr\/publications\/series\/rp-2021\/2024\/rp21-12-24.html\">Statec: RP2021 N\u00b012 \u2013 Les r\u00e9sidents actifs \u2013 Un emploi dynamique et segment\u00e9<\/a><\/strong><\/span><\/p>\n<p><strong>Gut zu wissen<\/strong>: Wenn Sie sich bei einem Unternehmen bewerben m\u00f6chten, sollten Sie sich vorher dar\u00fcber informieren, welche Sprachen dort jeweils gesprochen werden. W\u00e4hrend in der Finanzbranche Englisch zwingende Voraussetzung ist, um eingestellt zu werden, sind etwa in Banken mit Ursprung in deutschsprachigen L\u00e4ndern und in Logistikunternehmen, die eng mit den Nachbarl\u00e4ndern Luxemburgs jenseits der Mosel zusammenarbeiten, Bewerber mit Deutschkenntnissen sehr gefragt.<\/p>\n<p><strong>Ein gro\u00dfes Angebot an Sprachkursen<\/strong><\/p>\n<p>Sollten Sie in Luxemburg nach einem Sprachkurs f\u00fcr Anf\u00e4nger oder Fortgeschrittene f\u00fcr eine der Landessprachen suchen, so d\u00fcrften Sie v\u00f6llig problemlos f\u00fcndig werden. Luxemburgischkurse erfreuen sich immer gr\u00f6\u00dferer Beliebtheit, insbesondere seit der Reform des luxemburgischen <a href=\"https:\/\/my-life.lu\/de\/wie-erwerbe-ich-die-luxemburgische-staatsangehoerigkeit-59009\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Staatsangeh\u00f6rigkeitsgesetzes<\/strong><\/span><\/a>, gem\u00e4\u00df dem ein Mindestma\u00df an Luxemburgischkenntnissen erforderlich ist.<\/p>\n<p><a href=\"https:\/\/my-life.lu\/de\/fuenf-gute-gruende-fuer-eine-weiterbildung-56039\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Sprachkurse f\u00fcr Erwachsene<\/strong><\/span><\/a>\u00a0werden nicht nur vom Nationalen Spracheninstitut (Institut national des langues \u2013 INL) angeboten, sondern auch innerhalb der Berufskammern sowie in bestimmten Schulen und Gymnasien. Dar\u00fcber hinaus gibt es eine ganze Reihe von privaten Einrichtungen, die unterschiedliche Formen von Privat- und Gruppenunterricht f\u00fcr Privatpersonen und Unternehmen anbieten, die als Pr\u00e4senzveranstaltung oder \u00fcber das Internet oder Telefon usw. stattfinden k\u00f6nnen.<\/p>\n<p>Falls Sie Hilfe dabei ben\u00f6tigen, den f\u00fcr Sie passenden Kurs zu finden, empfehlen wir Ihnen das <a href=\"https:\/\/www.lifelong-learning.lu\/accueil\/de\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Portal lifelong-learning.lu<\/strong><\/span><\/a>. Dort finden Sie eine breite Palette von Kursen.<\/p>\n<p><strong>Gut zu wissen<\/strong>: Wenn Sie neben Ihrer Berufst\u00e4tigkeit Ihre Luxemburgischkenntnisse verbessern m\u00f6chten, haben Sie die M\u00f6glichkeit, Sonderurlaub zur sprachlichen Weiterbildung zu beantragen. In diesem Rahmen stehen Ihnen w\u00e4hrend Ihrer gesamten beruflichen Laufbahn insgesamt 200\u00a0Stunden zu. Fragen Sie hierzu einfach Ihren Arbeitgeber.<\/p>\n<blockquote><p>Die Schulen in Luxemburg sind mehrsprachig. Den Kindern kommt zugute, dass der Unterricht je nach Alter und Klassenstufe in unterschiedlichen Sprachen stattfindet.<\/p><\/blockquote>\n<h2 id=\"h2_2\" >Ein mehrsprachiges Schulkonzept<\/h2>\n<p>Eine der Besonderheiten Luxemburgs besteht darin, dass seine Schulen mehrsprachig sind. Kinder aus Zuwandererfamilien kommt zugute, dass der Unterricht je nach Alter und <a href=\"https:\/\/my-life.lu\/de\/wissenswertes-ueber-das-schulsystem-in-luxemburg-57011\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Klassenstufe<\/strong><\/span><\/a> in unterschiedlichen Sprachen stattfindet.<\/p>\n<p>Die Lehrerinnen und Lehrer sprechen mit den Kindern w\u00e4hrend des ersten Zyklus, d.h. in der Grundschule (<em>enseignement fondamental<\/em>), haupts\u00e4chlich Luxemburgisch, und f\u00fchren sie allm\u00e4hlich an Franz\u00f6sisch heran. Anschlie\u00dfend wird der Unterricht auf Luxemburgisch, Deutsch und\/oder Franz\u00f6sisch abgehalten. So werden die Sch\u00fclerinnen und Sch\u00fcler w\u00e4hrend ihrer Schulzeit mit mindestens drei Sprachen konfrontiert\u00a0\u2013 zus\u00e4tzlich zu den in der Sekundarstufe (ab 12\u00a0Jahren) erlernten Sprachen, wie Englisch, Italienisch, Portugiesisch, Spanisch oder Chinesisch.<\/p>\n<p><strong>Gut zu wissen<\/strong>: Kinder aus Zuwandererfamilien, die die im Unterricht verwendete Sprache nicht beherrschen, k\u00f6nnen an einem Integrationskurs teilnehmen oder Sprachf\u00f6rderkurse in Luxemburgisch oder Deutsch besuchen, um ihre Integration zu erleichtern. Zudem gibt es in Luxemburg europ\u00e4ische und internationale Schulen, in denen die Unterrichtssprache Englisch oder Franz\u00f6sisch ist.<\/p>\n<blockquote><p>Die Luxemburger k\u00f6nnen ganz einfach mitten im Gespr\u00e4ch von einer Sprache in die andere wechseln.<\/p><\/blockquote>\n<h2 id=\"h2_3\" >Welche Sprache(n) wird\/werden in Luxemburg im Alltag verwendet?<\/h2>\n<p>Auch im Alltag manifestiert sich die Vielsprachigkeit Luxemburgs, und die Sprachen vermischen sich auf nat\u00fcrliche Weise miteinander. Wundern Sie sich also nicht, wenn Sie Luxemburger erleben, die ganz einfach mitten im Gespr\u00e4ch von einer Sprache in die andere wechseln. Sowas ist alles andere als ungew\u00f6hnlich!<\/p>\n<p>Wenn Sie Ihren Wocheneinkauf erledigen oder eine Shopping-Tour machen, spricht man in der Regel Franz\u00f6sisch, Luxemburgisch, Englisch oder Deutsch mit Ihnen. Im Restaurant wird man Franz\u00f6sisch oder Englisch mit Ihnen sprechen. Je nach Art des Gastronomiebetriebs k\u00f6nnen Sie Ihre Bestellung sogar auf Italienisch, Portugiesisch, Spanisch usw. aufgeben. Zeitungen (sowohl als Printausgabe als auch online) werden in der Regel auf Luxemburgisch herausgegeben, sind aber auch auf Deutsch, Englisch, Franz\u00f6sisch und Portugiesisch verf\u00fcgbar. Krankenhausmitarbeiter beherrschen im Allgemeinen alle drei Landessprachen. Gleiches gilt f\u00fcr Mitarbeiter von Verwaltungseinrichtungen, wie etwa der Gemeinden, Steuerbeh\u00f6rden, Sozialversicherung, Banken, Versicherungsgesellschaften usw.<\/p>\n<p><strong>Gut zu wissen<\/strong>: Auch das kulturelle Leben in Luxemburg ist mehrsprachig. So werden beispielsweise in vielen Buchhandlungen B\u00fccher in mehreren Sprachen angeboten, das Theaterprogramm ist international ausgerichtet, und Kinofilme werden in ihrer Originalfassung mit franz\u00f6sischen, deutschen oder niederl\u00e4ndischen Untertiteln gezeigt.<\/p>\n<p>Obwohl der Gebrauch der einzelnen Sprachen in Luxemburg sehr facettenreich ist, stellen Luxemburgischkenntnisse einen gro\u00dfen Vorteil dar und k\u00f6nnen Zuwanderern die Integration deutlich erleichtern\u00a0\u2013 sowohl privat als auch im Berufsleben. Wer seine S\u00e4tze mit einem \u201eVillmools Merci\u201c oder einem \u201e\u00c4ddi\u201c beendet, beim Betreten einer Einrichtung mit \u201eMoien\u201c oder \u201eGudde Owend\u201c gr\u00fc\u00dft und in der Lage ist, mit dem Nachbarn ein paar Worte auf Luxemburgisch zu wechseln, kann sich damit leicht Freunde machen. Z\u00f6gern Sie also nicht, diese Sprache mit ihren vielf\u00e4ltigen Einfl\u00fcssen zu erlernen, denn sie wird es Ihnen erm\u00f6glichen, besser in die Landeskultur einzutauchen! Bis geschw\u00ebnn!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie planen, nach Luxemburg auszuwandern und sich dort Arbeit zu suchen? Die meisten administrativen Schritte im Zusammenhang mit Ihren Auswanderungspl\u00e4nen haben Sie bereits erledigt, doch es gibt noch ein Thema, das Ihnen Sorgen bereitet: die Sprache Ihrer neuen Wahlheimat. Welche Sprache(n) sollte man wann und wo in diesem bekannterma\u00dfen mehrsprachigen Land verwenden? myLIFE gibt Ihnen &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Welche Sprachen spricht man in Luxemburg?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":13554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","beyondwords_generate_audio":"1","beyondwords_integration_method":"","beyondwords_project_id":"44704","beyondwords_content_id":"0ed90a7d-7e0d-4e25-b396-7893ae46b75b","beyondwords_preview_token":"d4b70c1c-fb20-4c25-ba40-c3edb0670515","beyondwords_player_content":"","beyondwords_player_style":"standard","beyondwords_language_code":"de_DE","beyondwords_language_id":"44","beyondwords_title_voice_id":"2138","beyondwords_body_voice_id":"2138","beyondwords_summary_voice_id":"2138","beyondwords_error_message":"","beyondwords_disabled":"","beyondwords_delete_content":"","beyondwords_podcast_id":"0ed90a7d-7e0d-4e25-b396-7893ae46b75b","beyondwords_hash":"","publish_post_to_speechkit":"","speechkit_hash":"","speechkit_generate_audio":"","speechkit_project_id":"","speechkit_podcast_id":"","speechkit_error_message":"","speechkit_disabled":"","speechkit_access_key":"","speechkit_error":"","speechkit_info":"","speechkit_response":"","speechkit_retries":"","speechkit_status":"","speechkit_updated_at":"","_speechkit_link":"","_speechkit_text":""},"categories":[2,161],"tags":[454,582],"class_list":["post-13566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-me-and-my-family-de","category-freizeit-de","tag-freizeit","tag-kontakt-de","my_family"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Welche Sprachen spricht man in Luxemburg? - myLIFE<\/title>\n<meta name=\"description\" content=\"Sie sind eben erst nach Luxemburg gezogen? Und Sie fragen sich, welche Sprachen dort im Alltag und auf der Arbeit gesprochen werden? myLIFE erkl\u00e4rt es Ihnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welche Sprachen spricht man in Luxemburg?\" \/>\n<meta property=\"og:description\" content=\"Sie sind eben erst nach Luxemburg gezogen? Und Sie fragen sich, welche Sprachen dort im Alltag und auf der Arbeit gesprochen werden? myLIFE erkl\u00e4rt es Ihnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/\" \/>\n<meta property=\"og:site_name\" content=\"myLIFE\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-09T08:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-13T12:55:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/my-life.lu\/wp-content\/uploads\/2020\/10\/Article_59017-e1726231491169.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Compiled by myLIFE team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gesammelt von myLIFE team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/\"},\"author\":{\"name\":\"Compiled by myLIFE team\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#\\\/schema\\\/person\\\/224f7e554674eb9534cbab8498cd369b\"},\"headline\":\"Welche Sprachen spricht man in Luxemburg?\",\"datePublished\":\"2020-11-09T08:00:45+00:00\",\"dateModified\":\"2024-09-13T12:55:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/\"},\"wordCount\":1251,\"publisher\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Article_59017-e1726231491169.jpg\",\"keywords\":[\"Freizeit\",\"Kontakt\"],\"articleSection\":[\"me&amp;myFAMILY\",\"Freizeit\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/\",\"url\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/\",\"name\":\"Welche Sprachen spricht man in Luxemburg? - myLIFE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Article_59017-e1726231491169.jpg\",\"datePublished\":\"2020-11-09T08:00:45+00:00\",\"dateModified\":\"2024-09-13T12:55:57+00:00\",\"description\":\"Sie sind eben erst nach Luxemburg gezogen? Und Sie fragen sich, welche Sprachen dort im Alltag und auf der Arbeit gesprochen werden? myLIFE erkl\u00e4rt es Ihnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Article_59017-e1726231491169.jpg\",\"contentUrl\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Article_59017-e1726231491169.jpg\",\"width\":1920,\"height\":1442},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/welche-sprachen-spricht-man-in-luxemburg-59017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/my-life.lu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Welche Sprachen spricht man in Luxemburg?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/my-life.lu\\\/de\\\/\",\"name\":\"myLIFE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/my-life.lu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#organization\",\"name\":\"myLIFE\",\"url\":\"https:\\\/\\\/my-life.lu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/myLIFE_LOGO_violet-AMP2.png\",\"contentUrl\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/myLIFE_LOGO_violet-AMP2.png\",\"width\":190,\"height\":36,\"caption\":\"myLIFE\"},\"image\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#\\\/schema\\\/person\\\/224f7e554674eb9534cbab8498cd369b\",\"name\":\"Compiled by myLIFE team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g\",\"caption\":\"Compiled by myLIFE team\"},\"url\":\"https:\\\/\\\/my-life.lu\\\/de\\\/author\\\/compiled-by-mylife-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Welche Sprachen spricht man in Luxemburg? - myLIFE","description":"Sie sind eben erst nach Luxemburg gezogen? Und Sie fragen sich, welche Sprachen dort im Alltag und auf der Arbeit gesprochen werden? myLIFE erkl\u00e4rt es Ihnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/","og_locale":"de_DE","og_type":"article","og_title":"Welche Sprachen spricht man in Luxemburg?","og_description":"Sie sind eben erst nach Luxemburg gezogen? Und Sie fragen sich, welche Sprachen dort im Alltag und auf der Arbeit gesprochen werden? myLIFE erkl\u00e4rt es Ihnen.","og_url":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/","og_site_name":"myLIFE","article_published_time":"2020-11-09T08:00:45+00:00","article_modified_time":"2024-09-13T12:55:57+00:00","og_image":[{"width":1920,"height":1442,"url":"https:\/\/my-life.lu\/wp-content\/uploads\/2020\/10\/Article_59017-e1726231491169.jpg","type":"image\/jpeg"}],"author":"Compiled by myLIFE team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gesammelt von myLIFE team","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/#article","isPartOf":{"@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/"},"author":{"name":"Compiled by myLIFE team","@id":"https:\/\/my-life.lu\/de\/#\/schema\/person\/224f7e554674eb9534cbab8498cd369b"},"headline":"Welche Sprachen spricht man in Luxemburg?","datePublished":"2020-11-09T08:00:45+00:00","dateModified":"2024-09-13T12:55:57+00:00","mainEntityOfPage":{"@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/"},"wordCount":1251,"publisher":{"@id":"https:\/\/my-life.lu\/de\/#organization"},"image":{"@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/#primaryimage"},"thumbnailUrl":"https:\/\/my-life.lu\/wp-content\/uploads\/2020\/10\/Article_59017-e1726231491169.jpg","keywords":["Freizeit","Kontakt"],"articleSection":["me&amp;myFAMILY","Freizeit"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/","url":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/","name":"Welche Sprachen spricht man in Luxemburg? - myLIFE","isPartOf":{"@id":"https:\/\/my-life.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/#primaryimage"},"image":{"@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/#primaryimage"},"thumbnailUrl":"https:\/\/my-life.lu\/wp-content\/uploads\/2020\/10\/Article_59017-e1726231491169.jpg","datePublished":"2020-11-09T08:00:45+00:00","dateModified":"2024-09-13T12:55:57+00:00","description":"Sie sind eben erst nach Luxemburg gezogen? Und Sie fragen sich, welche Sprachen dort im Alltag und auf der Arbeit gesprochen werden? myLIFE erkl\u00e4rt es Ihnen.","breadcrumb":{"@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/#primaryimage","url":"https:\/\/my-life.lu\/wp-content\/uploads\/2020\/10\/Article_59017-e1726231491169.jpg","contentUrl":"https:\/\/my-life.lu\/wp-content\/uploads\/2020\/10\/Article_59017-e1726231491169.jpg","width":1920,"height":1442},{"@type":"BreadcrumbList","@id":"https:\/\/my-life.lu\/de\/welche-sprachen-spricht-man-in-luxemburg-59017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/my-life.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Welche Sprachen spricht man in Luxemburg?"}]},{"@type":"WebSite","@id":"https:\/\/my-life.lu\/de\/#website","url":"https:\/\/my-life.lu\/de\/","name":"myLIFE","description":"","publisher":{"@id":"https:\/\/my-life.lu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/my-life.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/my-life.lu\/de\/#organization","name":"myLIFE","url":"https:\/\/my-life.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/my-life.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/my-life.lu\/wp-content\/uploads\/2018\/07\/myLIFE_LOGO_violet-AMP2.png","contentUrl":"https:\/\/my-life.lu\/wp-content\/uploads\/2018\/07\/myLIFE_LOGO_violet-AMP2.png","width":190,"height":36,"caption":"myLIFE"},"image":{"@id":"https:\/\/my-life.lu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/my-life.lu\/de\/#\/schema\/person\/224f7e554674eb9534cbab8498cd369b","name":"Compiled by myLIFE team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g","caption":"Compiled by myLIFE team"},"url":"https:\/\/my-life.lu\/de\/author\/compiled-by-mylife-team\/"}]}},"_links":{"self":[{"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/posts\/13566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/comments?post=13566"}],"version-history":[{"count":5,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/posts\/13566\/revisions"}],"predecessor-version":[{"id":24306,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/posts\/13566\/revisions\/24306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/media\/13554"}],"wp:attachment":[{"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/media?parent=13566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/categories?post=13566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/tags?post=13566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}