{"id":3601,"date":"2017-11-30T10:42:59","date_gmt":"2017-11-30T09:42:59","guid":{"rendered":"https:\/\/my-life.lu\/?p=3601\/"},"modified":"2018-07-19T16:32:53","modified_gmt":"2018-07-19T14:32:53","slug":"ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021","status":"publish","type":"post","link":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/","title":{"rendered":"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps"},"content":{"rendered":"<div id=\"playht-iframe-wrapper\" style=\"max-height: 210px !important;\">\n\t<iframe\n\tscrolling=\"no\"\n\tclass=\"playht-iframe-player\"\n\tid=\"playht-iframe-player\"\n\theight=\"90px\"\n\twidth=\"100%\"\n\tframeborder=\"0\"\n\tstyle=\"max-height: 90px; height: 90px !important;\"\n\tsrc=\"https:\/\/play.ht\/embed\/?article_url=https:\/\/my-life.lu\/de\/?p=3601&voice=de-DE-Wavenet-C&appId=fiFJxxWiUV3tImG&trans_id=-MJgbWe3Ja4l-dYZGOeU\"\n\tdata-voice=\"de-DE-Wavenet-C\"\n\tarticle-url=\"https:\/\/my-life.lu\/de\/?p=3601\"\n\tdata-appId=\"fiFJxxWiUV3tImG\"\n\tallowfullscreen=\"\">\n\t<\/iframe>\n<\/div>\n<p class=\"entete\">Unser ehrw\u00fcrdiger Kollege Professor Nabil hat Sie vor kurzem an seinem Fachwissen teilhaben lassen, indem er <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/my-life.lu\/de\/tipps-von-professor-nabil-lektion-1-wie-investieren-ohne-sich-zu-ruinieren-30010\/\" target=\"_blank\" rel=\"noopener\">wertvolle Tipps f\u00fcr sicheres Anlegen<\/a><\/strong><\/span> \u00a0auf der myLIFE-Plattform gab.<\/p>\n<p>In diesem Zusammenhang m\u00f6chten wir hier auf einige Aspekte der Verhaltens\u00f6konomie eingehen, die es in Verbindung mit der traditionellen Finanzanalyse gestatten, sich in Anlagefragen besser zurechtzufinden. Denken Sie immer daran, dass die traditionelle Finanzanalyse aus der Wirtschaftswissenschaft hervorgegangen ist. Diese ist zwar auch eine Wissenschaft, geh\u00f6rt allerdings zu den Humanwissenschaften und ist daher nicht exakt.<\/p>\n<p>Der Nobelpreis f\u00fcr Wirtschaft ging in diesem Jahr an Professor Richard H. Thaler von der Universit\u00e4t Chicago f\u00fcr seinen Beitrag zur Verhaltens\u00f6konomie. Bei der Pressekonferenz erkl\u00e4rte er, er werde versuchen, das Preisgeld \u201eso irrational wie m\u00f6glich auszugeben\u201c. Dabei trug er ein Sweatshirt mit der Aufschrift \u201eQuasi Rational\u201c.<\/p>\n<blockquote><p><em>Denken Sie immer daran, dass die traditionelle Finanzanalyse aus der Wirtschaftswissenschaft hervorgegangen ist.<\/em><\/p><\/blockquote>\n<p>Denken Sie immer daran, dass die traditionelle Finanzanalyse aus der Wirtschaftswissenschaft hervorgegangen ist.<\/p>\n<p>Das Gegenteil ist aber noch symptomatischer! Finanzielle Verluste reizen die gleiche Hirnregion, die auch auf Lebensgefahren reagiert. Daher kann eine Risikoscheu als Reaktion auf einen finanziellen Fehlschlag nicht absch\u00e4tzbare Folgen f\u00fcr das Verm\u00f6gen haben, wenn man sich in Zeiten der Panik auf den B\u00f6rsenm\u00e4rkten vom \u00dcberlebensinstinkt leiten l\u00e4sst.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3590\" src=\"https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton-1024x1024.jpg\" alt=\"\" width=\"180\" height=\"180\" srcset=\"https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton-1024x1024.jpg 1024w, https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton-150x150.jpg 150w, https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton-300x300.jpg 300w, https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton-768x768.jpg 768w, https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton-1080x1080.jpg 1080w, https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton-100x100.jpg 100w, https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton-467x467.jpg 467w, https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Mouton.jpg 1181w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/p>\n<p>Das Ph\u00e4nomen des \u201eSocial Proof\u201c oder Herdentriebs kann man auch auf den Finanzm\u00e4rkten beobachten. Es bedeutet, dass viele Menschen sich darauf beschr\u00e4nken, andere zu beobachten und deren Verhaltensweisen kopieren, um sich sicher zu f\u00fchlen. Ebenso tendiert man, wenn man sieht, dass ein Ereignis sich in gleicher Weise wiederholt, fast automatisch und unbewusst dazu, zu glauben, dass es sich noch ein weiteres Mal wiederholt.<\/p>\n<p>Hei\u00dft das, dass wir f\u00e4hig sind, die Zukunft vorherzusagen, Unvorhergesehenes vorauszuahnen und genaue Aussagen \u00fcber die Welt von morgen zu treffen? Wahrscheinlich nicht. Auch aus diesem Grund f\u00fchlt man sich sicherer, wenn man der Masse folgt. Oder sollte man stattdessen einen gegens\u00e4tzlichen, gewagten Ansatz verfolgen? Das k\u00f6nnte man nat\u00fcrlich auch, aber es ist mit Sicherheit keine Universall\u00f6sung. Fehler einzugestehen und daraus zu lernen, ist ohne Zweifel ein Weg zum Erfolg. Das gilt auch in der Anlageverwaltung.<\/p>\n<p>Abschlie\u00dfend noch ein Tipp in Anlehnung an Professor Nabil: Seien Sie mutig, aber bleiben Sie immer bescheiden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser ehrw\u00fcrdiger Kollege Professor Nabil hat Sie vor kurzem an seinem Fachwissen teilhaben lassen, indem er wertvolle Tipps f\u00fcr sicheres Anlegen \u00a0auf der myLIFE-Plattform gab. In diesem Zusammenhang m\u00f6chten wir hier auf einige Aspekte der Verhaltens\u00f6konomie eingehen, die es in Verbindung mit der traditionellen Finanzanalyse gestatten, sich in Anlagefragen besser zurechtzufinden. Denken Sie immer daran, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps&#8221;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":4524,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","beyondwords_generate_audio":"","beyondwords_integration_method":"","beyondwords_project_id":"","beyondwords_content_id":"","beyondwords_preview_token":"","beyondwords_player_content":"","beyondwords_player_style":"","beyondwords_language_code":"","beyondwords_language_id":"","beyondwords_title_voice_id":"","beyondwords_body_voice_id":"","beyondwords_summary_voice_id":"","beyondwords_error_message":"","beyondwords_disabled":"","beyondwords_delete_content":"","beyondwords_podcast_id":"","beyondwords_hash":"","publish_post_to_speechkit":"","speechkit_hash":"","speechkit_generate_audio":"","speechkit_project_id":"","speechkit_podcast_id":"","speechkit_error_message":"","speechkit_disabled":"","speechkit_access_key":"","speechkit_error":"","speechkit_info":"","speechkit_response":"","speechkit_retries":"","speechkit_status":"","speechkit_updated_at":"","_speechkit_link":"","_speechkit_text":""},"categories":[187,189,16],"tags":[429,442,450],"class_list":["post-3601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sparen-de-2","category-investitionen-de","category-myinvest-de","tag-anlegerprofil","tag-investitionen","tag-sparen","my_invest"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps - myLIFE<\/title>\n<meta name=\"description\" content=\"Es gibt verschiedene Arten von Anlagen, die ebenso zug\u00e4nglich wie interessant sind. Man muss nur wissen, wo man sucht und wie man vorgeht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps\" \/>\n<meta property=\"og:description\" content=\"Es gibt verschiedene Arten von Anlagen, die ebenso zug\u00e4nglich wie interessant sind. Man muss nur wissen, wo man sucht und wie man vorgeht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/\" \/>\n<meta property=\"og:site_name\" content=\"myLIFE\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-30T09:42:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-19T14:32:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Article_30021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1914\" \/>\n\t<meta property=\"og:image:height\" content=\"1369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Compiled by myLIFE team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gesammelt von myLIFE team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/\"},\"author\":{\"name\":\"Compiled by myLIFE team\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#\\\/schema\\\/person\\\/224f7e554674eb9534cbab8498cd369b\"},\"headline\":\"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps\",\"datePublished\":\"2017-11-30T09:42:59+00:00\",\"dateModified\":\"2018-07-19T14:32:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Article_30021.jpg\",\"keywords\":[\"Anlegerprofil\",\"Investitionen\",\"Sparen\"],\"articleSection\":[\"Sparen\",\"Investitionen\",\"myINVEST\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/\",\"url\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/\",\"name\":\"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps - myLIFE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Article_30021.jpg\",\"datePublished\":\"2017-11-30T09:42:59+00:00\",\"dateModified\":\"2018-07-19T14:32:53+00:00\",\"description\":\"Es gibt verschiedene Arten von Anlagen, die ebenso zug\u00e4nglich wie interessant sind. Man muss nur wissen, wo man sucht und wie man vorgeht.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Article_30021.jpg\",\"contentUrl\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Article_30021.jpg\",\"width\":1914,\"height\":1369},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/my-life.lu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/my-life.lu\\\/de\\\/\",\"name\":\"myLIFE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/my-life.lu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#organization\",\"name\":\"myLIFE\",\"url\":\"https:\\\/\\\/my-life.lu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/myLIFE_LOGO_violet-AMP2.png\",\"contentUrl\":\"https:\\\/\\\/my-life.lu\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/myLIFE_LOGO_violet-AMP2.png\",\"width\":190,\"height\":36,\"caption\":\"myLIFE\"},\"image\":{\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/my-life.lu\\\/de\\\/#\\\/schema\\\/person\\\/224f7e554674eb9534cbab8498cd369b\",\"name\":\"Compiled by myLIFE team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g\",\"caption\":\"Compiled by myLIFE team\"},\"url\":\"https:\\\/\\\/my-life.lu\\\/de\\\/author\\\/compiled-by-mylife-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps - myLIFE","description":"Es gibt verschiedene Arten von Anlagen, die ebenso zug\u00e4nglich wie interessant sind. Man muss nur wissen, wo man sucht und wie man vorgeht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/","og_locale":"de_DE","og_type":"article","og_title":"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps","og_description":"Es gibt verschiedene Arten von Anlagen, die ebenso zug\u00e4nglich wie interessant sind. Man muss nur wissen, wo man sucht und wie man vorgeht.","og_url":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/","og_site_name":"myLIFE","article_published_time":"2017-11-30T09:42:59+00:00","article_modified_time":"2018-07-19T14:32:53+00:00","og_image":[{"width":1914,"height":1369,"url":"https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Article_30021.jpg","type":"image\/jpeg"}],"author":"Compiled by myLIFE team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gesammelt von myLIFE team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/#article","isPartOf":{"@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/"},"author":{"name":"Compiled by myLIFE team","@id":"https:\/\/my-life.lu\/de\/#\/schema\/person\/224f7e554674eb9534cbab8498cd369b"},"headline":"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps","datePublished":"2017-11-30T09:42:59+00:00","dateModified":"2018-07-19T14:32:53+00:00","mainEntityOfPage":{"@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/"},"wordCount":398,"publisher":{"@id":"https:\/\/my-life.lu\/de\/#organization"},"image":{"@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/#primaryimage"},"thumbnailUrl":"https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Article_30021.jpg","keywords":["Anlegerprofil","Investitionen","Sparen"],"articleSection":["Sparen","Investitionen","myINVEST"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/","url":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/","name":"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps - myLIFE","isPartOf":{"@id":"https:\/\/my-life.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/#primaryimage"},"image":{"@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/#primaryimage"},"thumbnailUrl":"https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Article_30021.jpg","datePublished":"2017-11-30T09:42:59+00:00","dateModified":"2018-07-19T14:32:53+00:00","description":"Es gibt verschiedene Arten von Anlagen, die ebenso zug\u00e4nglich wie interessant sind. Man muss nur wissen, wo man sucht und wie man vorgeht.","breadcrumb":{"@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/#primaryimage","url":"https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Article_30021.jpg","contentUrl":"https:\/\/my-life.lu\/wp-content\/uploads\/2017\/11\/Article_30021.jpg","width":1914,"height":1369},{"@type":"BreadcrumbList","@id":"https:\/\/my-life.lu\/de\/ein-kleiner-wink-professor-nabil-lektion-1-ein-paar-zusaetzliche-tipps-30021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/my-life.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Ein kleiner Wink an Professor Nabil (Lektion 1): ein paar zus\u00e4tzliche Tipps"}]},{"@type":"WebSite","@id":"https:\/\/my-life.lu\/de\/#website","url":"https:\/\/my-life.lu\/de\/","name":"myLIFE","description":"","publisher":{"@id":"https:\/\/my-life.lu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/my-life.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/my-life.lu\/de\/#organization","name":"myLIFE","url":"https:\/\/my-life.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/my-life.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/my-life.lu\/wp-content\/uploads\/2018\/07\/myLIFE_LOGO_violet-AMP2.png","contentUrl":"https:\/\/my-life.lu\/wp-content\/uploads\/2018\/07\/myLIFE_LOGO_violet-AMP2.png","width":190,"height":36,"caption":"myLIFE"},"image":{"@id":"https:\/\/my-life.lu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/my-life.lu\/de\/#\/schema\/person\/224f7e554674eb9534cbab8498cd369b","name":"Compiled by myLIFE team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28b395d9b8d5c7e9757fb0c7315ee854d88aef3f02f0c439e5813c8149eb6ecb?s=96&d=mm&r=g","caption":"Compiled by myLIFE team"},"url":"https:\/\/my-life.lu\/de\/author\/compiled-by-mylife-team\/"}]}},"_links":{"self":[{"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/posts\/3601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/comments?post=3601"}],"version-history":[{"count":2,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/posts\/3601\/revisions"}],"predecessor-version":[{"id":6397,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/posts\/3601\/revisions\/6397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/media\/4524"}],"wp:attachment":[{"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/media?parent=3601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/categories?post=3601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-life.lu\/de\/wp-json\/wp\/v2\/tags?post=3601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}